{"id":5472,"date":"2023-10-09T17:09:10","date_gmt":"2023-10-09T15:09:10","guid":{"rendered":"https:\/\/www.elspagesos.com\/event\/electronica-house-techno-2\/"},"modified":"2023-10-09T17:09:55","modified_gmt":"2023-10-09T15:09:55","slug":"electronica-house-techno-2","status":"publish","type":"event","link":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/","title":{"rendered":"ELECTR\u00d2NICA &#038; HOUSE &#038; TECHNO"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_458.jpg\" alt=\"ELECTR\u00d2NICA &#038; HOUSE &#038; TECHNO\" \/><\/p>\n<div>\n<p>\n\tGabriel Fern&aacute;ndez, Javi MARVEL amb vynil set, Oscar Jodan i JCG tornen a la c&agrave;rrega en una sessi&oacute; d&#39;electr&ograve;nica, techno i house.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gabriel Fern&aacute;ndez, Javi MARVEL amb vynil set, Oscar Jodan i JCG tornen a la c&agrave;rrega en una sessi&oacute; d&#39;electr&ograve;nica, techno i house.<\/p>\n","protected":false},"featured_media":2826,"menu_order":0,"template":"","class_list":["post-5472","event","type-event","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Gabriel Fern\u00e1ndez, Javi MARVEL amb vynil set, Oscar Jodan i JCG tornen a la c\u00e0rrega en una sessi\u00f3 d&#039;electr\u00f2nica, techno i house.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Els pagesos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"ELECTR\u00d2NICA &amp; HOUSE &amp; TECHNO - Els pagesos\" \/>\n\t\t<meta property=\"og:description\" content=\"Gabriel Fern\u00e1ndez, Javi MARVEL amb vynil set, Oscar Jodan i JCG tornen a la c\u00e0rrega en una sessi\u00f3 d&#039;electr\u00f2nica, techno i house.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-09T15:09:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-09T15:09:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"ELECTR\u00d2NICA &amp; HOUSE &amp; TECHNO - Els pagesos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Gabriel Fern\u00e1ndez, Javi MARVEL amb vynil set, Oscar Jodan i JCG tornen a la c\u00e0rrega en una sessi\u00f3 d&#039;electr\u00f2nica, techno i house.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/electronica-house-techno-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/electronica-house-techno-2\\\/#listItem\",\"name\":\"ELECTR\\u00d2NICA &#038; HOUSE &#038; TECHNO\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/electronica-house-techno-2\\\/#listItem\",\"position\":3,\"name\":\"ELECTR\\u00d2NICA &#038; HOUSE &#038; TECHNO\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\",\"name\":\"pagesos\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/electronica-house-techno-2\\\/#webpage\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/electronica-house-techno-2\\\/\",\"name\":\"ELECTR\\u00d2NICA & HOUSE & TECHNO - Els pagesos\",\"description\":\"Gabriel Fern\\u00e1ndez, Javi MARVEL amb vynil set, Oscar Jodan i JCG tornen a la c\\u00e0rrega en una sessi\\u00f3 d'electr\\u00f2nica, techno i house.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/electronica-house-techno-2\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/flyer_458.jpg\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/electronica-house-techno-2\\\/#mainImage\",\"width\":550,\"height\":778},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/electronica-house-techno-2\\\/#mainImage\"},\"datePublished\":\"2023-10-09T17:09:10+02:00\",\"dateModified\":\"2023-10-09T17:09:55+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"name\":\"pagesos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"ELECTR\u00d2NICA & HOUSE & TECHNO - Els pagesos","description":"Gabriel Fern\u00e1ndez, Javi MARVEL amb vynil set, Oscar Jodan i JCG tornen a la c\u00e0rrega en una sessi\u00f3 d'electr\u00f2nica, techno i house.","canonical_url":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","position":1,"name":"Inicio","item":"https:\/\/www.elspagesos.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/www.elspagesos.com\/es\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/#listItem","name":"ELECTR\u00d2NICA &#038; HOUSE &#038; TECHNO"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/#listItem","position":3,"name":"ELECTR\u00d2NICA &#038; HOUSE &#038; TECHNO","previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"Organization","@id":"https:\/\/www.elspagesos.com\/es\/#organization","name":"pagesos","url":"https:\/\/www.elspagesos.com\/es\/"},{"@type":"WebPage","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/#webpage","url":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/","name":"ELECTR\u00d2NICA & HOUSE & TECHNO - Els pagesos","description":"Gabriel Fern\u00e1ndez, Javi MARVEL amb vynil set, Oscar Jodan i JCG tornen a la c\u00e0rrega en una sessi\u00f3 d'electr\u00f2nica, techno i house.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.elspagesos.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_458.jpg","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/#mainImage","width":550,"height":778},"primaryImageOfPage":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/#mainImage"},"datePublished":"2023-10-09T17:09:10+02:00","dateModified":"2023-10-09T17:09:55+02:00"},{"@type":"WebSite","@id":"https:\/\/www.elspagesos.com\/es\/#website","url":"https:\/\/www.elspagesos.com\/es\/","name":"pagesos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.elspagesos.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Els pagesos -","og:type":"article","og:title":"ELECTR\u00d2NICA &amp; HOUSE &amp; TECHNO - Els pagesos","og:description":"Gabriel Fern\u00e1ndez, Javi MARVEL amb vynil set, Oscar Jodan i JCG tornen a la c\u00e0rrega en una sessi\u00f3 d'electr\u00f2nica, techno i house.","og:url":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/","article:published_time":"2023-10-09T15:09:10+00:00","article:modified_time":"2023-10-09T15:09:55+00:00","twitter:card":"summary_large_image","twitter:title":"ELECTR\u00d2NICA &amp; HOUSE &amp; TECHNO - Els pagesos","twitter:description":"Gabriel Fern\u00e1ndez, Javi MARVEL amb vynil set, Oscar Jodan i JCG tornen a la c\u00e0rrega en una sessi\u00f3 d'electr\u00f2nica, techno i house."},"aioseo_meta_data":{"post_id":"5472","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-09 14:32:07","updated":"2025-10-15 04:08:32","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tELECTR\u00d2NICA &amp; HOUSE &amp; TECHNO\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.elspagesos.com\/es\/"},{"label":"Agenda","link":"https:\/\/www.elspagesos.com\/es\/agenda\/"},{"label":"ELECTR\u00d2NICA &#038; HOUSE &#038; TECHNO","link":"https:\/\/www.elspagesos.com\/es\/agenda\/electronica-house-techno-2\/"}],"_links":{"self":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":1,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5472\/revisions"}],"predecessor-version":[{"id":6659,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5472\/revisions\/6659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media\/2826"}],"wp:attachment":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media?parent=5472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}