{"id":5371,"date":"2023-10-09T17:08:10","date_gmt":"2023-10-09T15:08:10","guid":{"rendered":"https:\/\/www.elspagesos.com\/event\/cine-documental-20-000-days-on-earth\/"},"modified":"2023-10-09T17:08:44","modified_gmt":"2023-10-09T15:08:44","slug":"cine-documental-20-000-days-on-earth","status":"publish","type":"event","link":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/","title":{"rendered":"CINE DOCUMENTAL: 20.000 Days on Earth"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_354.jpg\" alt=\"CINE DOCUMENTAL: 20.000 Days on Earth\" \/><\/p>\n<div>\n<p>\n\tUn any m&eacute;s, tornen els juliols de cinema i documental musicals a Els Pagesos i, enguany, amb setmanes tem&agrave;tiques. Aquesta setmana &eacute;s el torn de Nick Cave.<br \/>\n\t<strong><br \/>\n\tDimecres 21:<\/strong><br \/>\n\t<strong>20.000 DAYS ON EARTH<\/strong><br \/>\n\tAny: 2014<br \/>\n\tDurada: 95 min.<br \/>\n\tPais: Regne Unit<br \/>\n\tDirecci&oacute;: Iain Forsyth, Jane Pollard<\/p>\n<p>\t&quot;Drama y realidad se combinan en 24 horas ficticias en la vida del m&uacute;sico e icono cultural internacional Nick Cave. Con ideas sorprendentes y un &iacute;ntimo retrato del proceso art&iacute;stico, la pel&iacute;cula examina lo que nos hace ser lo que somos y celebra el poder transformador del esp&iacute;ritu creativo.&quot; (FILMAFFINITY)<\/p>\n<p>\t&nbsp;<\/p>\n<\/div>\n<p><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/Ap0_y5EGttk\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un any m&eacute;s, tornen els juliols de cinema i documental musicals a Els Pagesos i, enguany, amb setmanes tem&agrave;tiques. Aquesta setmana &eacute;s el torn de Nick Cave. Dimecres 21: 20.000 DAYS ON EARTH Any: 2014 Durada: 95 min. Pais: Regne Unit Direcci&oacute;: Iain Forsyth, Jane Pollard &quot;Drama y realidad se combinan en 24 horas ficticias [&hellip;]<\/p>\n","protected":false},"featured_media":2624,"menu_order":0,"template":"","class_list":["post-5371","event","type-event","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Un any m\u00e9s, tornen els juliols de cinema i documental musicals a Els Pagesos i, enguany, amb setmanes tem\u00e0tiques. Aquesta setmana \u00e9s el torn de Nick Cave. Dimecres 21: 20.000 DAYS ON EARTH Any: 2014 Durada: 95 min. Pais: Regne Unit Direcci\u00f3: Iain Forsyth, Jane Pollard &quot;Drama y realidad se combinan en 24 horas ficticias\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Els pagesos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"CINE DOCUMENTAL: 20.000 Days on Earth - Els pagesos\" \/>\n\t\t<meta property=\"og:description\" content=\"Un any m\u00e9s, tornen els juliols de cinema i documental musicals a Els Pagesos i, enguany, amb setmanes tem\u00e0tiques. Aquesta setmana \u00e9s el torn de Nick Cave. Dimecres 21: 20.000 DAYS ON EARTH Any: 2014 Durada: 95 min. Pais: Regne Unit Direcci\u00f3: Iain Forsyth, Jane Pollard &quot;Drama y realidad se combinan en 24 horas ficticias\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-09T15:08:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-09T15:08:44+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"CINE DOCUMENTAL: 20.000 Days on Earth - Els pagesos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Un any m\u00e9s, tornen els juliols de cinema i documental musicals a Els Pagesos i, enguany, amb setmanes tem\u00e0tiques. Aquesta setmana \u00e9s el torn de Nick Cave. Dimecres 21: 20.000 DAYS ON EARTH Any: 2014 Durada: 95 min. Pais: Regne Unit Direcci\u00f3: Iain Forsyth, Jane Pollard &quot;Drama y realidad se combinan en 24 horas ficticias\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/cine-documental-20-000-days-on-earth\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/cine-documental-20-000-days-on-earth\\\/#listItem\",\"name\":\"CINE DOCUMENTAL: 20.000 Days on Earth\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/cine-documental-20-000-days-on-earth\\\/#listItem\",\"position\":3,\"name\":\"CINE DOCUMENTAL: 20.000 Days on Earth\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\",\"name\":\"pagesos\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/cine-documental-20-000-days-on-earth\\\/#webpage\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/cine-documental-20-000-days-on-earth\\\/\",\"name\":\"CINE DOCUMENTAL: 20.000 Days on Earth - Els pagesos\",\"description\":\"Un any m\\u00e9s, tornen els juliols de cinema i documental musicals a Els Pagesos i, enguany, amb setmanes tem\\u00e0tiques. Aquesta setmana \\u00e9s el torn de Nick Cave. Dimecres 21: 20.000 DAYS ON EARTH Any: 2014 Durada: 95 min. Pais: Regne Unit Direcci\\u00f3: Iain Forsyth, Jane Pollard \\\"Drama y realidad se combinan en 24 horas ficticias\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/cine-documental-20-000-days-on-earth\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/flyer_354.jpg\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/cine-documental-20-000-days-on-earth\\\/#mainImage\",\"width\":550,\"height\":778},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/cine-documental-20-000-days-on-earth\\\/#mainImage\"},\"datePublished\":\"2023-10-09T17:08:10+02:00\",\"dateModified\":\"2023-10-09T17:08:44+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"name\":\"pagesos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"CINE DOCUMENTAL: 20.000 Days on Earth - Els pagesos","description":"Un any m\u00e9s, tornen els juliols de cinema i documental musicals a Els Pagesos i, enguany, amb setmanes tem\u00e0tiques. Aquesta setmana \u00e9s el torn de Nick Cave. Dimecres 21: 20.000 DAYS ON EARTH Any: 2014 Durada: 95 min. Pais: Regne Unit Direcci\u00f3: Iain Forsyth, Jane Pollard \"Drama y realidad se combinan en 24 horas ficticias","canonical_url":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","position":1,"name":"Inicio","item":"https:\/\/www.elspagesos.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/www.elspagesos.com\/es\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/#listItem","name":"CINE DOCUMENTAL: 20.000 Days on Earth"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/#listItem","position":3,"name":"CINE DOCUMENTAL: 20.000 Days on Earth","previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"Organization","@id":"https:\/\/www.elspagesos.com\/es\/#organization","name":"pagesos","url":"https:\/\/www.elspagesos.com\/es\/"},{"@type":"WebPage","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/#webpage","url":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/","name":"CINE DOCUMENTAL: 20.000 Days on Earth - Els pagesos","description":"Un any m\u00e9s, tornen els juliols de cinema i documental musicals a Els Pagesos i, enguany, amb setmanes tem\u00e0tiques. Aquesta setmana \u00e9s el torn de Nick Cave. Dimecres 21: 20.000 DAYS ON EARTH Any: 2014 Durada: 95 min. Pais: Regne Unit Direcci\u00f3: Iain Forsyth, Jane Pollard \"Drama y realidad se combinan en 24 horas ficticias","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.elspagesos.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_354.jpg","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/#mainImage","width":550,"height":778},"primaryImageOfPage":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/#mainImage"},"datePublished":"2023-10-09T17:08:10+02:00","dateModified":"2023-10-09T17:08:44+02:00"},{"@type":"WebSite","@id":"https:\/\/www.elspagesos.com\/es\/#website","url":"https:\/\/www.elspagesos.com\/es\/","name":"pagesos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.elspagesos.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Els pagesos -","og:type":"article","og:title":"CINE DOCUMENTAL: 20.000 Days on Earth - Els pagesos","og:description":"Un any m\u00e9s, tornen els juliols de cinema i documental musicals a Els Pagesos i, enguany, amb setmanes tem\u00e0tiques. Aquesta setmana \u00e9s el torn de Nick Cave. Dimecres 21: 20.000 DAYS ON EARTH Any: 2014 Durada: 95 min. Pais: Regne Unit Direcci\u00f3: Iain Forsyth, Jane Pollard &quot;Drama y realidad se combinan en 24 horas ficticias","og:url":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/","article:published_time":"2023-10-09T15:08:10+00:00","article:modified_time":"2023-10-09T15:08:44+00:00","twitter:card":"summary_large_image","twitter:title":"CINE DOCUMENTAL: 20.000 Days on Earth - Els pagesos","twitter:description":"Un any m\u00e9s, tornen els juliols de cinema i documental musicals a Els Pagesos i, enguany, amb setmanes tem\u00e0tiques. Aquesta setmana \u00e9s el torn de Nick Cave. Dimecres 21: 20.000 DAYS ON EARTH Any: 2014 Durada: 95 min. Pais: Regne Unit Direcci\u00f3: Iain Forsyth, Jane Pollard &quot;Drama y realidad se combinan en 24 horas ficticias"},"aioseo_meta_data":{"post_id":"5371","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-09 14:12:43","updated":"2025-10-15 02:26:15","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCINE DOCUMENTAL: 20.000 Days on Earth\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.elspagesos.com\/es\/"},{"label":"Agenda","link":"https:\/\/www.elspagesos.com\/es\/agenda\/"},{"label":"CINE DOCUMENTAL: 20.000 Days on Earth","link":"https:\/\/www.elspagesos.com\/es\/agenda\/cine-documental-20-000-days-on-earth\/"}],"_links":{"self":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":1,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5371\/revisions"}],"predecessor-version":[{"id":6443,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5371\/revisions\/6443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media\/2624"}],"wp:attachment":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media?parent=5371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}