{"id":5344,"date":"2023-10-09T17:07:57","date_gmt":"2023-10-09T15:07:57","guid":{"rendered":"https:\/\/www.elspagesos.com\/event\/william-wallace-enomix-stona\/"},"modified":"2023-10-09T17:08:25","modified_gmt":"2023-10-09T15:08:25","slug":"william-wallace-enomix-stona","status":"publish","type":"event","link":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/","title":{"rendered":"WILLIAM WALLACE + ENOMIX STONA"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_327.jpg\" alt=\"WILLIAM WALLACE + ENOMIX STONA\" \/><\/p>\n<div>\n<p>\n\tTornen el William Wallace i l&#39;itali&agrave; Enomix Stona amb els seus vinils a posar la banda sonora del vermut.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tornen el William Wallace i l&#39;itali&agrave; Enomix Stona amb els seus vinils a posar la banda sonora del vermut.<\/p>\n","protected":false},"featured_media":2570,"menu_order":0,"template":"","class_list":["post-5344","event","type-event","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tornen el William Wallace i l&#039;itali\u00e0 Enomix Stona amb els seus vinils a posar la banda sonora del vermut.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Els pagesos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"WILLIAM WALLACE + ENOMIX STONA - Els pagesos\" \/>\n\t\t<meta property=\"og:description\" content=\"Tornen el William Wallace i l&#039;itali\u00e0 Enomix Stona amb els seus vinils a posar la banda sonora del vermut.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-09T15:07:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-09T15:08:25+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"WILLIAM WALLACE + ENOMIX STONA - Els pagesos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tornen el William Wallace i l&#039;itali\u00e0 Enomix Stona amb els seus vinils a posar la banda sonora del vermut.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/william-wallace-enomix-stona\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/william-wallace-enomix-stona\\\/#listItem\",\"name\":\"WILLIAM WALLACE + ENOMIX STONA\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/william-wallace-enomix-stona\\\/#listItem\",\"position\":3,\"name\":\"WILLIAM WALLACE + ENOMIX STONA\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\",\"name\":\"pagesos\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/william-wallace-enomix-stona\\\/#webpage\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/william-wallace-enomix-stona\\\/\",\"name\":\"WILLIAM WALLACE + ENOMIX STONA - Els pagesos\",\"description\":\"Tornen el William Wallace i l'itali\\u00e0 Enomix Stona amb els seus vinils a posar la banda sonora del vermut.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/william-wallace-enomix-stona\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/flyer_327.jpg\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/william-wallace-enomix-stona\\\/#mainImage\",\"width\":550,\"height\":777},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/william-wallace-enomix-stona\\\/#mainImage\"},\"datePublished\":\"2023-10-09T17:07:57+02:00\",\"dateModified\":\"2023-10-09T17:08:25+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"name\":\"pagesos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"WILLIAM WALLACE + ENOMIX STONA - Els pagesos","description":"Tornen el William Wallace i l'itali\u00e0 Enomix Stona amb els seus vinils a posar la banda sonora del vermut.","canonical_url":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","position":1,"name":"Inicio","item":"https:\/\/www.elspagesos.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/www.elspagesos.com\/es\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/#listItem","name":"WILLIAM WALLACE + ENOMIX STONA"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/#listItem","position":3,"name":"WILLIAM WALLACE + ENOMIX STONA","previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"Organization","@id":"https:\/\/www.elspagesos.com\/es\/#organization","name":"pagesos","url":"https:\/\/www.elspagesos.com\/es\/"},{"@type":"WebPage","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/#webpage","url":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/","name":"WILLIAM WALLACE + ENOMIX STONA - Els pagesos","description":"Tornen el William Wallace i l'itali\u00e0 Enomix Stona amb els seus vinils a posar la banda sonora del vermut.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.elspagesos.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_327.jpg","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/#mainImage","width":550,"height":777},"primaryImageOfPage":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/#mainImage"},"datePublished":"2023-10-09T17:07:57+02:00","dateModified":"2023-10-09T17:08:25+02:00"},{"@type":"WebSite","@id":"https:\/\/www.elspagesos.com\/es\/#website","url":"https:\/\/www.elspagesos.com\/es\/","name":"pagesos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.elspagesos.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Els pagesos -","og:type":"article","og:title":"WILLIAM WALLACE + ENOMIX STONA - Els pagesos","og:description":"Tornen el William Wallace i l'itali\u00e0 Enomix Stona amb els seus vinils a posar la banda sonora del vermut.","og:url":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/","article:published_time":"2023-10-09T15:07:57+00:00","article:modified_time":"2023-10-09T15:08:25+00:00","twitter:card":"summary_large_image","twitter:title":"WILLIAM WALLACE + ENOMIX STONA - Els pagesos","twitter:description":"Tornen el William Wallace i l'itali\u00e0 Enomix Stona amb els seus vinils a posar la banda sonora del vermut."},"aioseo_meta_data":{"post_id":"5344","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-09 14:06:49","updated":"2025-10-15 02:10:33","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWILLIAM WALLACE + ENOMIX STONA\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.elspagesos.com\/es\/"},{"label":"Agenda","link":"https:\/\/www.elspagesos.com\/es\/agenda\/"},{"label":"WILLIAM WALLACE + ENOMIX STONA","link":"https:\/\/www.elspagesos.com\/es\/agenda\/william-wallace-enomix-stona\/"}],"_links":{"self":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":1,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5344\/revisions"}],"predecessor-version":[{"id":6384,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5344\/revisions\/6384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media\/2570"}],"wp:attachment":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media?parent=5344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}