{"id":5321,"date":"2023-10-09T17:07:45","date_gmt":"2023-10-09T15:07:45","guid":{"rendered":"https:\/\/www.elspagesos.com\/event\/the-mumbojambos-en-ensayo-abierto\/"},"modified":"2023-10-09T17:08:10","modified_gmt":"2023-10-09T15:08:10","slug":"the-mumbojambos-en-ensayo-abierto","status":"publish","type":"event","link":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/","title":{"rendered":"THE MUMBOJAMBOS en Ensayo Abierto"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_304.jpg\" alt=\"THE MUMBOJAMBOS en Ensayo Abierto\" \/><\/p>\n<div>\n<p>\n\tSe mueven entre la bossa y el funk pasando por el rock. Temas propios y covers. Este jueves, The MumboJumbos en ensayo abierto.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se mueven entre la bossa y el funk pasando por el rock. Temas propios y covers. Este jueves, The MumboJumbos en ensayo abierto.<\/p>\n","protected":false},"featured_media":1087,"menu_order":0,"template":"","class_list":["post-5321","event","type-event","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Se mueven entre la bossa y el funk pasando por el rock. Temas propios y covers. Este jueves, The MumboJumbos en ensayo abierto.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Els pagesos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"THE MUMBOJAMBOS en Ensayo Abierto - Els pagesos\" \/>\n\t\t<meta property=\"og:description\" content=\"Se mueven entre la bossa y el funk pasando por el rock. Temas propios y covers. Este jueves, The MumboJumbos en ensayo abierto.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-09T15:07:45+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-09T15:08:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"THE MUMBOJAMBOS en Ensayo Abierto - Els pagesos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Se mueven entre la bossa y el funk pasando por el rock. Temas propios y covers. Este jueves, The MumboJumbos en ensayo abierto.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/the-mumbojambos-en-ensayo-abierto\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/the-mumbojambos-en-ensayo-abierto\\\/#listItem\",\"name\":\"THE MUMBOJAMBOS en Ensayo Abierto\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/the-mumbojambos-en-ensayo-abierto\\\/#listItem\",\"position\":3,\"name\":\"THE MUMBOJAMBOS en Ensayo Abierto\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\",\"name\":\"pagesos\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/the-mumbojambos-en-ensayo-abierto\\\/#webpage\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/the-mumbojambos-en-ensayo-abierto\\\/\",\"name\":\"THE MUMBOJAMBOS en Ensayo Abierto - Els pagesos\",\"description\":\"Se mueven entre la bossa y el funk pasando por el rock. Temas propios y covers. Este jueves, The MumboJumbos en ensayo abierto.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/the-mumbojambos-en-ensayo-abierto\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/flyer_304.jpg\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/the-mumbojambos-en-ensayo-abierto\\\/#mainImage\",\"width\":550,\"height\":778},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/the-mumbojambos-en-ensayo-abierto\\\/#mainImage\"},\"datePublished\":\"2023-10-09T17:07:45+02:00\",\"dateModified\":\"2023-10-09T17:08:10+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"name\":\"pagesos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"THE MUMBOJAMBOS en Ensayo Abierto - Els pagesos","description":"Se mueven entre la bossa y el funk pasando por el rock. Temas propios y covers. Este jueves, The MumboJumbos en ensayo abierto.","canonical_url":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","position":1,"name":"Inicio","item":"https:\/\/www.elspagesos.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/www.elspagesos.com\/es\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/#listItem","name":"THE MUMBOJAMBOS en Ensayo Abierto"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/#listItem","position":3,"name":"THE MUMBOJAMBOS en Ensayo Abierto","previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"Organization","@id":"https:\/\/www.elspagesos.com\/es\/#organization","name":"pagesos","url":"https:\/\/www.elspagesos.com\/es\/"},{"@type":"WebPage","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/#webpage","url":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/","name":"THE MUMBOJAMBOS en Ensayo Abierto - Els pagesos","description":"Se mueven entre la bossa y el funk pasando por el rock. Temas propios y covers. Este jueves, The MumboJumbos en ensayo abierto.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.elspagesos.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_304.jpg","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/#mainImage","width":550,"height":778},"primaryImageOfPage":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/#mainImage"},"datePublished":"2023-10-09T17:07:45+02:00","dateModified":"2023-10-09T17:08:10+02:00"},{"@type":"WebSite","@id":"https:\/\/www.elspagesos.com\/es\/#website","url":"https:\/\/www.elspagesos.com\/es\/","name":"pagesos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.elspagesos.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Els pagesos -","og:type":"article","og:title":"THE MUMBOJAMBOS en Ensayo Abierto - Els pagesos","og:description":"Se mueven entre la bossa y el funk pasando por el rock. Temas propios y covers. Este jueves, The MumboJumbos en ensayo abierto.","og:url":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/","article:published_time":"2023-10-09T15:07:45+00:00","article:modified_time":"2023-10-09T15:08:10+00:00","twitter:card":"summary_large_image","twitter:title":"THE MUMBOJAMBOS en Ensayo Abierto - Els pagesos","twitter:description":"Se mueven entre la bossa y el funk pasando por el rock. Temas propios y covers. Este jueves, The MumboJumbos en ensayo abierto."},"aioseo_meta_data":{"post_id":"5321","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-09 14:02:30","updated":"2025-10-15 02:03:47","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTHE MUMBOJAMBOS en Ensayo Abierto\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.elspagesos.com\/es\/"},{"label":"Agenda","link":"https:\/\/www.elspagesos.com\/es\/agenda\/"},{"label":"THE MUMBOJAMBOS en Ensayo Abierto","link":"https:\/\/www.elspagesos.com\/es\/agenda\/the-mumbojambos-en-ensayo-abierto\/"}],"_links":{"self":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":1,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5321\/revisions"}],"predecessor-version":[{"id":6335,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5321\/revisions\/6335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media\/1087"}],"wp:attachment":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media?parent=5321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}