{"id":5248,"date":"2023-10-09T17:06:55","date_gmt":"2023-10-09T15:06:55","guid":{"rendered":"https:\/\/www.elspagesos.com\/event\/fiestas-de-primavera-dj-txarnego\/"},"modified":"2023-10-09T17:07:16","modified_gmt":"2023-10-09T15:07:16","slug":"fiestas-de-primavera-dj-txarnego","status":"publish","type":"event","link":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/","title":{"rendered":"FIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_218.jpg\" alt=\"FIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6\" \/><\/p>\n<div>\n<div>\n\t<\/p>\n<div>\n\t\tYa est&aacute; aqu&iacute;, ya lleg&oacute;, el flamenco y el wawanc&oacute;!<\/div>\n<div>\n\t\t&nbsp;<\/div>\n<div>\n\t\tCon <strong>Dj Txarneg&ouml;<\/strong> a los platos, <strong>rumba<\/strong>, <strong>boogaloo<\/strong> y <strong>funk<\/strong>. M&uacute;sica con sabor a vino fino y ron, para que se muevan las caderas (la de usted la primera) y, anticipando el verano, entre copa y copa, que suba la temperatura y de los cuerpos salte la ropa.<\/div>\n<div>\n\t\t&nbsp;<\/div>\n<div>\n\t\tDamas y caballeros, que comience la jarana, que el <em>Txarneg&ouml; Pinch<\/em><em>adiscos est&aacute; en la casa!<\/em><\/div>\n<div>\n\t\t&nbsp;<\/div>\n<p>\tEscucha una sesi&oacute;n<a href=\"https:\/\/www.mixcloud.com\/djtxarnego\/dj-txarnego-latinfunksoulboogaloo-vol3-62\/ \"> aqu&iacute;!<\/a><\/div>\n<\/div>\n<p><iframe width=\"552\" height=\"414\" src=\"https:\/\/www.youtube.com\/embed\/fOmxXw2aFbo\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est&aacute; aqu&iacute;, ya lleg&oacute;, el flamenco y el wawanc&oacute;! &nbsp; Con Dj Txarneg&ouml; a los platos, rumba, boogaloo y funk. M&uacute;sica con sabor a vino fino y ron, para que se muevan las caderas (la de usted la primera) y, anticipando el verano, entre copa y copa, que suba la temperatura y de los [&hellip;]<\/p>\n","protected":false},"featured_media":2356,"menu_order":0,"template":"","class_list":["post-5248","event","type-event","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ya est\u00e1 aqu\u00ed, ya lleg\u00f3, el flamenco y el wawanc\u00f3! Con Dj Txarneg\u00f6 a los platos, rumba, boogaloo y funk. M\u00fasica con sabor a vino fino y ron, para que se muevan las caderas (la de usted la primera) y, anticipando el verano, entre copa y copa, que suba la temperatura y de los\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Els pagesos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"FIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6 - Els pagesos\" \/>\n\t\t<meta property=\"og:description\" content=\"Ya est\u00e1 aqu\u00ed, ya lleg\u00f3, el flamenco y el wawanc\u00f3! Con Dj Txarneg\u00f6 a los platos, rumba, boogaloo y funk. M\u00fasica con sabor a vino fino y ron, para que se muevan las caderas (la de usted la primera) y, anticipando el verano, entre copa y copa, que suba la temperatura y de los\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-09T15:06:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-09T15:07:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"FIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6 - Els pagesos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ya est\u00e1 aqu\u00ed, ya lleg\u00f3, el flamenco y el wawanc\u00f3! Con Dj Txarneg\u00f6 a los platos, rumba, boogaloo y funk. M\u00fasica con sabor a vino fino y ron, para que se muevan las caderas (la de usted la primera) y, anticipando el verano, entre copa y copa, que suba la temperatura y de los\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/fiestas-de-primavera-dj-txarnego\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/fiestas-de-primavera-dj-txarnego\\\/#listItem\",\"name\":\"FIESTAS DE PRIMAVERA: DJ TXARNEG\\u00d6\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/fiestas-de-primavera-dj-txarnego\\\/#listItem\",\"position\":3,\"name\":\"FIESTAS DE PRIMAVERA: DJ TXARNEG\\u00d6\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\",\"name\":\"pagesos\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/fiestas-de-primavera-dj-txarnego\\\/#webpage\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/fiestas-de-primavera-dj-txarnego\\\/\",\"name\":\"FIESTAS DE PRIMAVERA: DJ TXARNEG\\u00d6 - Els pagesos\",\"description\":\"Ya est\\u00e1 aqu\\u00ed, ya lleg\\u00f3, el flamenco y el wawanc\\u00f3! Con Dj Txarneg\\u00f6 a los platos, rumba, boogaloo y funk. M\\u00fasica con sabor a vino fino y ron, para que se muevan las caderas (la de usted la primera) y, anticipando el verano, entre copa y copa, que suba la temperatura y de los\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/fiestas-de-primavera-dj-txarnego\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/flyer_218.jpg\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/fiestas-de-primavera-dj-txarnego\\\/#mainImage\",\"width\":550,\"height\":778},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/fiestas-de-primavera-dj-txarnego\\\/#mainImage\"},\"datePublished\":\"2023-10-09T17:06:55+02:00\",\"dateModified\":\"2023-10-09T17:07:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"name\":\"pagesos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"FIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6 - Els pagesos","description":"Ya est\u00e1 aqu\u00ed, ya lleg\u00f3, el flamenco y el wawanc\u00f3! Con Dj Txarneg\u00f6 a los platos, rumba, boogaloo y funk. M\u00fasica con sabor a vino fino y ron, para que se muevan las caderas (la de usted la primera) y, anticipando el verano, entre copa y copa, que suba la temperatura y de los","canonical_url":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","position":1,"name":"Inicio","item":"https:\/\/www.elspagesos.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/www.elspagesos.com\/es\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/#listItem","name":"FIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/#listItem","position":3,"name":"FIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6","previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"Organization","@id":"https:\/\/www.elspagesos.com\/es\/#organization","name":"pagesos","url":"https:\/\/www.elspagesos.com\/es\/"},{"@type":"WebPage","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/#webpage","url":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/","name":"FIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6 - Els pagesos","description":"Ya est\u00e1 aqu\u00ed, ya lleg\u00f3, el flamenco y el wawanc\u00f3! Con Dj Txarneg\u00f6 a los platos, rumba, boogaloo y funk. M\u00fasica con sabor a vino fino y ron, para que se muevan las caderas (la de usted la primera) y, anticipando el verano, entre copa y copa, que suba la temperatura y de los","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.elspagesos.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_218.jpg","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/#mainImage","width":550,"height":778},"primaryImageOfPage":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/#mainImage"},"datePublished":"2023-10-09T17:06:55+02:00","dateModified":"2023-10-09T17:07:16+02:00"},{"@type":"WebSite","@id":"https:\/\/www.elspagesos.com\/es\/#website","url":"https:\/\/www.elspagesos.com\/es\/","name":"pagesos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.elspagesos.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Els pagesos -","og:type":"article","og:title":"FIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6 - Els pagesos","og:description":"Ya est\u00e1 aqu\u00ed, ya lleg\u00f3, el flamenco y el wawanc\u00f3! Con Dj Txarneg\u00f6 a los platos, rumba, boogaloo y funk. M\u00fasica con sabor a vino fino y ron, para que se muevan las caderas (la de usted la primera) y, anticipando el verano, entre copa y copa, que suba la temperatura y de los","og:url":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/","article:published_time":"2023-10-09T15:06:55+00:00","article:modified_time":"2023-10-09T15:07:16+00:00","twitter:card":"summary_large_image","twitter:title":"FIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6 - Els pagesos","twitter:description":"Ya est\u00e1 aqu\u00ed, ya lleg\u00f3, el flamenco y el wawanc\u00f3! Con Dj Txarneg\u00f6 a los platos, rumba, boogaloo y funk. M\u00fasica con sabor a vino fino y ron, para que se muevan las caderas (la de usted la primera) y, anticipando el verano, entre copa y copa, que suba la temperatura y de los"},"aioseo_meta_data":{"post_id":"5248","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-09 13:09:51","updated":"2025-10-15 01:30:16","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.elspagesos.com\/es\/"},{"label":"Agenda","link":"https:\/\/www.elspagesos.com\/es\/agenda\/"},{"label":"FIESTAS DE PRIMAVERA: DJ TXARNEG\u00d6","link":"https:\/\/www.elspagesos.com\/es\/agenda\/fiestas-de-primavera-dj-txarnego\/"}],"_links":{"self":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":1,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5248\/revisions"}],"predecessor-version":[{"id":6176,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5248\/revisions\/6176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media\/2356"}],"wp:attachment":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media?parent=5248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}