{"id":5177,"date":"2023-10-09T17:06:07","date_gmt":"2023-10-09T15:06:07","guid":{"rendered":"https:\/\/www.elspagesos.com\/event\/mark-duffy-the-latxicos\/"},"modified":"2023-10-09T17:06:29","modified_gmt":"2023-10-09T15:06:29","slug":"mark-duffy-the-latxicos","status":"publish","type":"event","link":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/","title":{"rendered":"MARK DUFFY &#038; THE LATXICOS"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_145.jpg\" alt=\"MARK DUFFY &#038; THE LATXICOS\" \/><\/p>\n<div>\n<p>\n\tEl irland&eacute;s-santfeliuense Mark Duffy y su banda vuelven a la carga sobre los escenarios para presentarnos sus nuevos temas. Una mezcla de indie-folk con ra&iacute;ces, bases y ritmos irlandeses. Mucho m&aacute;s que duendes verdes y cerveza negra.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El irland&eacute;s-santfeliuense Mark Duffy y su banda vuelven a la carga sobre los escenarios para presentarnos sus nuevos temas. Una mezcla de indie-folk con ra&iacute;ces, bases y ritmos irlandeses. Mucho m&aacute;s que duendes verdes y cerveza negra.<\/p>\n","protected":false},"featured_media":2216,"menu_order":0,"template":"","class_list":["post-5177","event","type-event","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El irland\u00e9s-santfeliuense Mark Duffy y su banda vuelven a la carga sobre los escenarios para presentarnos sus nuevos temas. Una mezcla de indie-folk con ra\u00edces, bases y ritmos irlandeses. Mucho m\u00e1s que duendes verdes y cerveza negra.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Els pagesos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"MARK DUFFY &amp; THE LATXICOS - Els pagesos\" \/>\n\t\t<meta property=\"og:description\" content=\"El irland\u00e9s-santfeliuense Mark Duffy y su banda vuelven a la carga sobre los escenarios para presentarnos sus nuevos temas. Una mezcla de indie-folk con ra\u00edces, bases y ritmos irlandeses. Mucho m\u00e1s que duendes verdes y cerveza negra.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-09T15:06:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-09T15:06:29+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"MARK DUFFY &amp; THE LATXICOS - Els pagesos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El irland\u00e9s-santfeliuense Mark Duffy y su banda vuelven a la carga sobre los escenarios para presentarnos sus nuevos temas. Una mezcla de indie-folk con ra\u00edces, bases y ritmos irlandeses. Mucho m\u00e1s que duendes verdes y cerveza negra.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/mark-duffy-the-latxicos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/mark-duffy-the-latxicos\\\/#listItem\",\"name\":\"MARK DUFFY &#038; THE LATXICOS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/mark-duffy-the-latxicos\\\/#listItem\",\"position\":3,\"name\":\"MARK DUFFY &#038; THE LATXICOS\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\",\"name\":\"pagesos\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/mark-duffy-the-latxicos\\\/#webpage\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/mark-duffy-the-latxicos\\\/\",\"name\":\"MARK DUFFY & THE LATXICOS - Els pagesos\",\"description\":\"El irland\\u00e9s-santfeliuense Mark Duffy y su banda vuelven a la carga sobre los escenarios para presentarnos sus nuevos temas. Una mezcla de indie-folk con ra\\u00edces, bases y ritmos irlandeses. Mucho m\\u00e1s que duendes verdes y cerveza negra.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/mark-duffy-the-latxicos\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/flyer_145.jpg\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/mark-duffy-the-latxicos\\\/#mainImage\",\"width\":550,\"height\":275},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/mark-duffy-the-latxicos\\\/#mainImage\"},\"datePublished\":\"2023-10-09T17:06:07+02:00\",\"dateModified\":\"2023-10-09T17:06:29+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"name\":\"pagesos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"MARK DUFFY & THE LATXICOS - Els pagesos","description":"El irland\u00e9s-santfeliuense Mark Duffy y su banda vuelven a la carga sobre los escenarios para presentarnos sus nuevos temas. Una mezcla de indie-folk con ra\u00edces, bases y ritmos irlandeses. Mucho m\u00e1s que duendes verdes y cerveza negra.","canonical_url":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","position":1,"name":"Inicio","item":"https:\/\/www.elspagesos.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/www.elspagesos.com\/es\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/#listItem","name":"MARK DUFFY &#038; THE LATXICOS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/#listItem","position":3,"name":"MARK DUFFY &#038; THE LATXICOS","previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"Organization","@id":"https:\/\/www.elspagesos.com\/es\/#organization","name":"pagesos","url":"https:\/\/www.elspagesos.com\/es\/"},{"@type":"WebPage","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/#webpage","url":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/","name":"MARK DUFFY & THE LATXICOS - Els pagesos","description":"El irland\u00e9s-santfeliuense Mark Duffy y su banda vuelven a la carga sobre los escenarios para presentarnos sus nuevos temas. Una mezcla de indie-folk con ra\u00edces, bases y ritmos irlandeses. Mucho m\u00e1s que duendes verdes y cerveza negra.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.elspagesos.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_145.jpg","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/#mainImage","width":550,"height":275},"primaryImageOfPage":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/#mainImage"},"datePublished":"2023-10-09T17:06:07+02:00","dateModified":"2023-10-09T17:06:29+02:00"},{"@type":"WebSite","@id":"https:\/\/www.elspagesos.com\/es\/#website","url":"https:\/\/www.elspagesos.com\/es\/","name":"pagesos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.elspagesos.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Els pagesos -","og:type":"article","og:title":"MARK DUFFY &amp; THE LATXICOS - Els pagesos","og:description":"El irland\u00e9s-santfeliuense Mark Duffy y su banda vuelven a la carga sobre los escenarios para presentarnos sus nuevos temas. Una mezcla de indie-folk con ra\u00edces, bases y ritmos irlandeses. Mucho m\u00e1s que duendes verdes y cerveza negra.","og:url":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/","article:published_time":"2023-10-09T15:06:07+00:00","article:modified_time":"2023-10-09T15:06:29+00:00","twitter:card":"summary_large_image","twitter:title":"MARK DUFFY &amp; THE LATXICOS - Els pagesos","twitter:description":"El irland\u00e9s-santfeliuense Mark Duffy y su banda vuelven a la carga sobre los escenarios para presentarnos sus nuevos temas. Una mezcla de indie-folk con ra\u00edces, bases y ritmos irlandeses. Mucho m\u00e1s que duendes verdes y cerveza negra."},"aioseo_meta_data":{"post_id":"5177","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-09 12:55:09","updated":"2025-10-15 00:51:40","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMARK DUFFY &amp; THE LATXICOS\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.elspagesos.com\/es\/"},{"label":"Agenda","link":"https:\/\/www.elspagesos.com\/es\/agenda\/"},{"label":"MARK DUFFY &#038; THE LATXICOS","link":"https:\/\/www.elspagesos.com\/es\/agenda\/mark-duffy-the-latxicos\/"}],"_links":{"self":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":1,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5177\/revisions"}],"predecessor-version":[{"id":6029,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5177\/revisions\/6029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media\/2216"}],"wp:attachment":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media?parent=5177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}