{"id":5157,"date":"2023-10-09T17:05:55","date_gmt":"2023-10-09T15:05:55","guid":{"rendered":"https:\/\/www.elspagesos.com\/event\/linia-maginot\/"},"modified":"2023-10-09T17:06:16","modified_gmt":"2023-10-09T15:06:16","slug":"linia-maginot","status":"publish","type":"event","link":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/","title":{"rendered":"L\u00cdNIA MAGINOT"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_125.jpg\" alt=\"L\u00cdNIA MAGINOT\" \/><\/p>\n<div>\n<p>\n\t&nbsp;<\/p>\n<div>\n\t<strong>L&iacute;nia Magino<\/strong>t es un proyecto que ha juntado a Mag&iacute; Mestres, ex-miembro de &ldquo;La Brigada&rdquo;, Pau Alb&agrave;, bater&iacute;a de &ldquo;Tokyo Sex Destruction&rdquo; y &ldquo;Les Sueques&rdquo;, Jordi Ferret, bajista de &ldquo;Gentle Music Men&rdquo; y Guillem Alb&agrave;, actor i m&uacute;sico, para crear unas canciones mel&oacute;dicas con arreglos cuidados y voces angelicales.<\/div>\n<div>\n\t&nbsp;<\/div>\n<div>\n\tLa banda sali&oacute; a la luz el 1 de enero de 2012 con el single de su demo de debut: &ldquo;<a href=\"https:\/\/soundcloud.com\/paualba78\/bones-intencions-l-nia\"><strong>Bones Intencions<\/strong><\/a>&rdquo;.<\/div>\n<div>\n\t&nbsp;<\/div>\n<div>\n\tAhora tienes la&nbsp;oportunidad de veurlos y escucharlos en directo. No te los pierdas!<\/div>\n<div>\n\t&nbsp;<\/div>\n<div>\n\t<strong><a href=\"http:\/\/www.facebook.com\/liniamaginot\">Su Facebook<\/a><\/strong><\/div>\n<\/div>\n<p><iframe width=\"552\" height=\"311\" src=\"http:\/\/www.youtube.com\/embed\/v4vSjQbRYkI\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; L&iacute;nia Maginot es un proyecto que ha juntado a Mag&iacute; Mestres, ex-miembro de &ldquo;La Brigada&rdquo;, Pau Alb&agrave;, bater&iacute;a de &ldquo;Tokyo Sex Destruction&rdquo; y &ldquo;Les Sueques&rdquo;, Jordi Ferret, bajista de &ldquo;Gentle Music Men&rdquo; y Guillem Alb&agrave;, actor i m&uacute;sico, para crear unas canciones mel&oacute;dicas con arreglos cuidados y voces angelicales. &nbsp; La banda sali&oacute; a [&hellip;]<\/p>\n","protected":false},"featured_media":2176,"menu_order":0,"template":"","class_list":["post-5157","event","type-event","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"L\u00ednia Maginot es un proyecto que ha juntado a Mag\u00ed Mestres, ex-miembro de \u201cLa Brigada\u201d, Pau Alb\u00e0, bater\u00eda de \u201cTokyo Sex Destruction\u201d y \u201cLes Sueques\u201d, Jordi Ferret, bajista de \u201cGentle Music Men\u201d y Guillem Alb\u00e0, actor i m\u00fasico, para crear unas canciones mel\u00f3dicas con arreglos cuidados y voces angelicales. La banda sali\u00f3 a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Els pagesos -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"L\u00cdNIA MAGINOT - Els pagesos\" \/>\n\t\t<meta property=\"og:description\" content=\"L\u00ednia Maginot es un proyecto que ha juntado a Mag\u00ed Mestres, ex-miembro de \u201cLa Brigada\u201d, Pau Alb\u00e0, bater\u00eda de \u201cTokyo Sex Destruction\u201d y \u201cLes Sueques\u201d, Jordi Ferret, bajista de \u201cGentle Music Men\u201d y Guillem Alb\u00e0, actor i m\u00fasico, para crear unas canciones mel\u00f3dicas con arreglos cuidados y voces angelicales. La banda sali\u00f3 a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-09T15:05:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-09T15:06:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"L\u00cdNIA MAGINOT - Els pagesos\" \/>\n\t\t<meta name=\"twitter:description\" content=\"L\u00ednia Maginot es un proyecto que ha juntado a Mag\u00ed Mestres, ex-miembro de \u201cLa Brigada\u201d, Pau Alb\u00e0, bater\u00eda de \u201cTokyo Sex Destruction\u201d y \u201cLes Sueques\u201d, Jordi Ferret, bajista de \u201cGentle Music Men\u201d y Guillem Alb\u00e0, actor i m\u00fasico, para crear unas canciones mel\u00f3dicas con arreglos cuidados y voces angelicales. La banda sali\u00f3 a\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/linia-maginot\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/linia-maginot\\\/#listItem\",\"name\":\"L\\u00cdNIA MAGINOT\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/linia-maginot\\\/#listItem\",\"position\":3,\"name\":\"L\\u00cdNIA MAGINOT\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/#listItem\",\"name\":\"Agenda\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\",\"name\":\"pagesos\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/linia-maginot\\\/#webpage\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/linia-maginot\\\/\",\"name\":\"L\\u00cdNIA MAGINOT - Els pagesos\",\"description\":\"L\\u00ednia Maginot es un proyecto que ha juntado a Mag\\u00ed Mestres, ex-miembro de \\u201cLa Brigada\\u201d, Pau Alb\\u00e0, bater\\u00eda de \\u201cTokyo Sex Destruction\\u201d y \\u201cLes Sueques\\u201d, Jordi Ferret, bajista de \\u201cGentle Music Men\\u201d y Guillem Alb\\u00e0, actor i m\\u00fasico, para crear unas canciones mel\\u00f3dicas con arreglos cuidados y voces angelicales. La banda sali\\u00f3 a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/linia-maginot\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/flyer_125.jpg\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/linia-maginot\\\/#mainImage\",\"width\":550,\"height\":275},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/agenda\\\/linia-maginot\\\/#mainImage\"},\"datePublished\":\"2023-10-09T17:05:55+02:00\",\"dateModified\":\"2023-10-09T17:06:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/\",\"name\":\"pagesos\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elspagesos.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"L\u00cdNIA MAGINOT - Els pagesos","description":"L\u00ednia Maginot es un proyecto que ha juntado a Mag\u00ed Mestres, ex-miembro de \u201cLa Brigada\u201d, Pau Alb\u00e0, bater\u00eda de \u201cTokyo Sex Destruction\u201d y \u201cLes Sueques\u201d, Jordi Ferret, bajista de \u201cGentle Music Men\u201d y Guillem Alb\u00e0, actor i m\u00fasico, para crear unas canciones mel\u00f3dicas con arreglos cuidados y voces angelicales. La banda sali\u00f3 a","canonical_url":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","position":1,"name":"Inicio","item":"https:\/\/www.elspagesos.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","position":2,"name":"Agenda","item":"https:\/\/www.elspagesos.com\/es\/agenda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/#listItem","name":"L\u00cdNIA MAGINOT"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/#listItem","position":3,"name":"L\u00cdNIA MAGINOT","previousItem":{"@type":"ListItem","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/#listItem","name":"Agenda"}}]},{"@type":"Organization","@id":"https:\/\/www.elspagesos.com\/es\/#organization","name":"pagesos","url":"https:\/\/www.elspagesos.com\/es\/"},{"@type":"WebPage","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/#webpage","url":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/","name":"L\u00cdNIA MAGINOT - Els pagesos","description":"L\u00ednia Maginot es un proyecto que ha juntado a Mag\u00ed Mestres, ex-miembro de \u201cLa Brigada\u201d, Pau Alb\u00e0, bater\u00eda de \u201cTokyo Sex Destruction\u201d y \u201cLes Sueques\u201d, Jordi Ferret, bajista de \u201cGentle Music Men\u201d y Guillem Alb\u00e0, actor i m\u00fasico, para crear unas canciones mel\u00f3dicas con arreglos cuidados y voces angelicales. La banda sali\u00f3 a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.elspagesos.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.elspagesos.com\/wp-content\/uploads\/2023\/10\/flyer_125.jpg","@id":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/#mainImage","width":550,"height":275},"primaryImageOfPage":{"@id":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/#mainImage"},"datePublished":"2023-10-09T17:05:55+02:00","dateModified":"2023-10-09T17:06:16+02:00"},{"@type":"WebSite","@id":"https:\/\/www.elspagesos.com\/es\/#website","url":"https:\/\/www.elspagesos.com\/es\/","name":"pagesos","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.elspagesos.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Els pagesos -","og:type":"article","og:title":"L\u00cdNIA MAGINOT - Els pagesos","og:description":"L\u00ednia Maginot es un proyecto que ha juntado a Mag\u00ed Mestres, ex-miembro de \u201cLa Brigada\u201d, Pau Alb\u00e0, bater\u00eda de \u201cTokyo Sex Destruction\u201d y \u201cLes Sueques\u201d, Jordi Ferret, bajista de \u201cGentle Music Men\u201d y Guillem Alb\u00e0, actor i m\u00fasico, para crear unas canciones mel\u00f3dicas con arreglos cuidados y voces angelicales. La banda sali\u00f3 a","og:url":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/","article:published_time":"2023-10-09T15:05:55+00:00","article:modified_time":"2023-10-09T15:06:16+00:00","twitter:card":"summary_large_image","twitter:title":"L\u00cdNIA MAGINOT - Els pagesos","twitter:description":"L\u00ednia Maginot es un proyecto que ha juntado a Mag\u00ed Mestres, ex-miembro de \u201cLa Brigada\u201d, Pau Alb\u00e0, bater\u00eda de \u201cTokyo Sex Destruction\u201d y \u201cLes Sueques\u201d, Jordi Ferret, bajista de \u201cGentle Music Men\u201d y Guillem Alb\u00e0, actor i m\u00fasico, para crear unas canciones mel\u00f3dicas con arreglos cuidados y voces angelicales. La banda sali\u00f3 a"},"aioseo_meta_data":{"post_id":"5157","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-09 12:50:41","updated":"2025-10-15 00:42:27","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.elspagesos.com\/es\/agenda\/\" title=\"Agenda\">Agenda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tL\u00cdNIA MAGINOT\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.elspagesos.com\/es\/"},{"label":"Agenda","link":"https:\/\/www.elspagesos.com\/es\/agenda\/"},{"label":"L\u00cdNIA MAGINOT","link":"https:\/\/www.elspagesos.com\/es\/agenda\/linia-maginot\/"}],"_links":{"self":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":1,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5157\/revisions"}],"predecessor-version":[{"id":5986,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/event\/5157\/revisions\/5986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media\/2176"}],"wp:attachment":[{"href":"https:\/\/www.elspagesos.com\/es\/wp-json\/wp\/v2\/media?parent=5157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}